{"id":328,"count":1,"description":"","link":"https:\/\/drivelab.ee\/en\/product-category\/tools\/tool-storage\/","name":"Tool Storage","slug":"tool-storage","taxonomy":"product_cat","parent":327,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tool Storage Archives - DriveLab<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drivelab.ee\/en\/product-category\/tools\/tool-storage\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tool Storage Archives - DriveLab\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drivelab.ee\/en\/product-category\/tools\/tool-storage\/\" \/>\n<meta property=\"og:site_name\" content=\"DriveLab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/drivelab.ee\\\/product-category\\\/tools\\\/tool-storage\\\/\",\"url\":\"https:\\\/\\\/drivelab.ee\\\/product-category\\\/tools\\\/tool-storage\\\/\",\"name\":\"Tool Storage Archives - DriveLab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drivelab.ee\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drivelab.ee\\\/product-category\\\/tools\\\/tool-storage\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drivelab.ee\\\/product-category\\\/tools\\\/tool-storage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/drivelab.ee\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tools\",\"item\":\"https:\\\/\\\/drivelab.ee\\\/product-category\\\/tools\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tool Storage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drivelab.ee\\\/#website\",\"url\":\"https:\\\/\\\/drivelab.ee\\\/\",\"name\":\"DriveLab.ee\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/drivelab.ee\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drivelab.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/drivelab.ee\\\/#organization\",\"name\":\"DriveLab\",\"url\":\"https:\\\/\\\/drivelab.ee\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/drivelab.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/drivelab.ee\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/test-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/drivelab.ee\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/test-logo-1.png\",\"width\":492,\"height\":95,\"caption\":\"DriveLab\"},\"image\":{\"@id\":\"https:\\\/\\\/drivelab.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tool Storage Archives - DriveLab","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drivelab.ee\/en\/product-category\/tools\/tool-storage\/","og_locale":"en_US","og_type":"article","og_title":"Tool Storage Archives - DriveLab","og_url":"https:\/\/drivelab.ee\/en\/product-category\/tools\/tool-storage\/","og_site_name":"DriveLab","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/drivelab.ee\/product-category\/tools\/tool-storage\/","url":"https:\/\/drivelab.ee\/product-category\/tools\/tool-storage\/","name":"Tool Storage Archives - DriveLab","isPartOf":{"@id":"https:\/\/drivelab.ee\/#website"},"breadcrumb":{"@id":"https:\/\/drivelab.ee\/product-category\/tools\/tool-storage\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/drivelab.ee\/product-category\/tools\/tool-storage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/drivelab.ee\/"},{"@type":"ListItem","position":2,"name":"Tools","item":"https:\/\/drivelab.ee\/product-category\/tools\/"},{"@type":"ListItem","position":3,"name":"Tool Storage"}]},{"@type":"WebSite","@id":"https:\/\/drivelab.ee\/#website","url":"https:\/\/drivelab.ee\/","name":"DriveLab.ee","description":"","publisher":{"@id":"https:\/\/drivelab.ee\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drivelab.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/drivelab.ee\/#organization","name":"DriveLab","url":"https:\/\/drivelab.ee\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/drivelab.ee\/#\/schema\/logo\/image\/","url":"https:\/\/drivelab.ee\/wp-content\/uploads\/2025\/01\/test-logo-1.png","contentUrl":"https:\/\/drivelab.ee\/wp-content\/uploads\/2025\/01\/test-logo-1.png","width":492,"height":95,"caption":"DriveLab"},"image":{"@id":"https:\/\/drivelab.ee\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/drivelab.ee\/en\/wp-json\/wp\/v2\/product_cat\/328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drivelab.ee\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/drivelab.ee\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/drivelab.ee\/en\/wp-json\/wp\/v2\/product_cat\/327"}],"wp:post_type":[{"href":"https:\/\/drivelab.ee\/en\/wp-json\/wp\/v2\/product?product_cat=328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}